{"id":5998,"date":"2024-08-07T20:55:15","date_gmt":"2024-08-07T18:55:15","guid":{"rendered":"https:\/\/staging.pt\/bouchedev\/cirurgia-maxilo-facial\/"},"modified":"2025-06-13T08:50:24","modified_gmt":"2025-06-13T08:50:24","slug":"cirurgia-maxilo-facial-bouche-dental-group","status":"publish","type":"page","link":"https:\/\/bouchedentalgroup.lu\/pt-pt\/cirurgia-maxilo-facial-bouche-dental-group\/","title":{"rendered":"Cirurgia Maxilo-facial"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5998\" class=\"elementor elementor-5998 elementor-2549\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a45d37 e-flex e-con-boxed e-con e-parent\" data-id=\"5a45d37\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69aba11 e-flex e-con-boxed e-con e-parent\" data-id=\"69aba11\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-037bb7a elementor-widget elementor-widget-heading\" data-id=\"037bb7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cirurgia Maxilo-facial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f79a9d3 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f79a9d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9a0b41 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f9a0b41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O departamento de cirurgia maxilo-facial, est\u00e1 dedicado ao diagn\u00f3stico e tratamento cir\u00fargico das altera\u00e7\u00f5es no desenvolvimento \u00f3sseo facial do adulto.<\/p>\n<p>Designa-se por cirurgia maxilo-facial a interven\u00e7\u00e3o que corrige as assimetrias dentofaciais com o objetivo de alcan\u00e7ar um equil\u00edbrio perfeito da face e dos dentes. As dismorfias dentofaciais s\u00e3o bastante frequentes na popula\u00e7\u00e3o em geral. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40cc091 e-flex e-con-boxed e-con e-parent\" data-id=\"40cc091\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-56b33c1 e-con-full e-flex e-con e-child\" data-id=\"56b33c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20e7b2f elementor-widget elementor-widget-heading\" data-id=\"20e7b2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cirurgia Maxilo-facial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33b2508 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"33b2508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ap\u00f3s um per\u00edodo vari\u00e1vel de tratamento ortod\u00f4ntico, a interven\u00e7\u00e3o \u00e9 realizada nos maxilares para alcan\u00e7ar um equil\u00edbrio perfeito entre todas as caracter\u00edsticas faciais do individuo, uma oclus\u00e3o correta e melhoria da respira\u00e7\u00e3o (conseguindo uma maior passagem de ar atrav\u00e9s da via a\u00e9rea superior).<\/p>\n<p>\u00c0 medida que alteramos a posi\u00e7\u00e3o dos maxilares para a frente, para atr\u00e1s, acima ou abaixo, os tecidos faciais macios tamb\u00e9m se movem com elas, ou seja, o queixo, os l\u00e1bios, as bochechas e a extremidade do nariz, a altura do rosto at\u00e9 muda. <\/p>\n<p>Assim, uma vez que o maxilar \u00e9 colocado numa posi\u00e7\u00e3o correta, o perfil maxilo-facial torna-se correto e produz-se uma harmonia das novas caracter\u00edsticas faciais.<\/p>\n<p>A cirurgia maxilo-facial est\u00e1 intimamente relacionada \u00e0 Ortodontia e, normalmente, o tratamento come\u00e7a com a extra\u00e7\u00e3o dos dentes do siso, seguida de um tratamento ortod\u00f4ntico pr\u00e9vio \u00e0 cirurgia que dura entre 1 e 2 anos, em coopera\u00e7\u00e3o com o ortodontista. <\/p>\n<p>Este tempo pode ser menor, dependendo do caso. Portanto, a corre\u00e7\u00e3o das deformidades dento-maxilo-faciais envolve sempre um trabalho conjunto entre o ortodontista e o cirurgi\u00e3o. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91ee139 elementor-widget elementor-widget-button\" data-id=\"91ee139\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#footer_contactos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Marcar Consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-50dfd24 e-con-full e-flex e-con e-child\" data-id=\"50dfd24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-087ac03 elementor-widget elementor-widget-image\" data-id=\"087ac03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"409\" height=\"511\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_132121-Maxillofacial-Surgery.webp\" class=\"attachment-large size-large wp-image-5556\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_132121-Maxillofacial-Surgery.webp 409w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_132121-Maxillofacial-Surgery-240x300.webp 240w\" sizes=\"auto, (max-width: 409px) 100vw, 409px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-45cb57e e-flex e-con-boxed e-con e-parent\" data-id=\"45cb57e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-49ac926 e-con-full e-flex e-con e-child\" data-id=\"49ac926\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c1dfb1 elementor-widget elementor-widget-image\" data-id=\"6c1dfb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"301\" height=\"391\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_13252-parodontologie.webp\" class=\"attachment-large size-large wp-image-5558\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_13252-parodontologie.webp 301w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_13252-parodontologie-231x300.webp 231w\" sizes=\"auto, (max-width: 301px) 100vw, 301px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db48acc e-con-full e-flex e-con e-child\" data-id=\"db48acc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-618771f elementor-widget elementor-widget-heading\" data-id=\"618771f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Deformidade Dento-Facial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e37cd elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d2e37cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>As dismorfias dentofaciais s\u00e3o bastante frequentes na popula\u00e7\u00e3o em geral. Normalmente as pessoas identificam que t\u00eam dificuldade em mastigar porque os dentes n\u00e3o encaixam bem ou por notarem uma altera\u00e7\u00e3o no tamanho do queixo, com influ\u00eancia negativa na sua auto estima. <\/p>\n<p>Os problemas onde a cirurgia maxilo-facial \u00e9 indicada s\u00e3o:<\/p>\n<ul>\n<li>Prognatismo mandibular ou \u201cqueixo grande\u201d;<\/li>\n<li>Retrognatismo ou \u201cqueixo pequeno\u201d;<\/li>\n<li>Sorriso gengival ou \u201cgengiva a mostra\u201d;<\/li>\n<li>Mordida aberta ou \u201d os dentes n\u00e3o batem afrente ou atras\u201d;<\/li>\n<li>Mordidas cruzadas e assimetria facial ou \u201cface torta ou desviada\u201d.<\/li>\n<\/ul>\n<p>Estas altera\u00e7\u00f5es \u00f3sseas, resultam numa posi\u00e7\u00e3o incorreta dos dentes, com impacto negativo na harmonia\/est\u00e9tica maxilo-facial. Podem surgir de uma forma isolada ou associadas entre elas. O plano de tratamento deve ser individualizado para um melhor resultado funcional e est\u00e9tico. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b76b1f7 e-flex e-con-boxed e-con e-parent\" data-id=\"b76b1f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-34dfc9a e-con-full e-flex e-con e-child\" data-id=\"34dfc9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89ca889 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"89ca889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O tratamento com a cirurgia maxilo-facial \u00e9 um procedimento que engloba, sempre, a associa\u00e7\u00e3o de um tratamento ortod\u00f4ntico antes e depois da cirurgia. Ap\u00f3s realiza\u00e7\u00e3o da cirurgia ortogn\u00e1tica deve estar sempre associado tratamento de reabilita\u00e7\u00e3o intensivo. <\/p>\n<p>As altera\u00e7\u00f5es no comprimento, largura ou altura do maxilar traduzem-se em dificuldade no alojamento dos dentes e tamb\u00e9m na altera\u00e7\u00e3o da rela\u00e7\u00e3o entre os dentes superiores e inferiores. Os dentes tentam adaptar-se a essa falta ou excesso de osso, adotando posi\u00e7\u00f5es diferentes daquelas que teriam se a estrutura estivesse correta. <\/p>\n<p>Mostrar excessivamente a gengiva ao sorrir, n\u00e3o conseguir juntar completamente os l\u00e1bios sem esfor\u00e7o, n\u00e3o mostrar os dentes superiores ao sorrir, maxilar para tr\u00e1s, maxilar para a frente, dentes tortos na maxila, assimetrias faciais, queixo para tr\u00e1s, queixo para a frente, s\u00e3o algumas das principais queixas da popula\u00e7\u00e3o em geral.<\/p>\n<p>Esses problemas, sendo dos maxilares e dentes, devem ser tratados em conjunto com a Ortodontia (para corrigir a posi\u00e7\u00e3o dent\u00e1ria adotada) e a cirurgia (para colocar os maxilares na posi\u00e7\u00e3o correta), caso contr\u00e1rio, podem-se alcan\u00e7ar resultados insatisfat\u00f3rios ou tratamentos ortod\u00f4nticos indefinidos e recorrentes. <\/p>\n<p>Muitas vezes, as assimetrias na face s\u00e3o bastante significativas,como por exemplo, o queixo desviado com um compromisso est\u00e9tico importante.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fb1c0b1 e-flex e-con-boxed e-con e-parent\" data-id=\"fb1c0b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d592152 e-flex e-con-boxed e-con e-parent\" data-id=\"d592152\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2ff5b2a e-con-full e-flex e-con e-child\" data-id=\"2ff5b2a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51226d5 elementor-widget elementor-widget-heading\" data-id=\"51226d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quais s\u00e3o as altera\u00e7\u00f5es faciais e as m\u00e1s oclus\u00f5es mais comuns?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a58171b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a58171b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como j\u00e1 mencionado, quando existe uma discrep\u00e2ncia entre a posi\u00e7\u00e3o do osso maxilar e a mand\u00edbula, obt\u00e9m-se o que se conhece como m\u00e1 oclus\u00e3o esquel\u00e9tica, que pode ser de dois tipos em rela\u00e7\u00e3o ao plano antero-posterior:<\/p>\n<ul>\n<li><strong>CLASSE 2<\/strong>: tamb\u00e9m conhecido como retrognatismo mandibular e\/ou prognatismo maxilar. Ocorre quando o maxilar est\u00e1 avan\u00e7ado em rela\u00e7\u00e3o \u00e0 mand\u00edbula. <\/li>\n<li><strong>CLASSE 3<\/strong>: tamb\u00e9m conhecido como prognatismo mandibular e\/ou retrognatismo maxilar. Ocorre quando a mand\u00edbula est\u00e1 avan\u00e7ada em rela\u00e7\u00e3o \u00e0 maxila. <\/li>\n<\/ul>\n<p>Outros problemas comuns de m\u00e1 oclus\u00e3o s\u00e3o palato estreito, mordida aberta, mordida cruzada, mordida \u201ctopo a topo\u201d, sobremordida ou apinhamento dent\u00e1rio.<\/p>\n<p>Para al\u00e9m das m\u00e1s oclus\u00f5es, a m\u00e1 coloca\u00e7\u00e3o dos ossos da mand\u00edbula tamb\u00e9m pode causar outras malforma\u00e7\u00f5es, tais como:<\/p>\n<ul>\n<li><strong>Assimetria facial<\/strong>: quando um lado, ou uma parte de um lado da face, est\u00e1 desequilibrado com o outro ;<\/li>\n<li><strong>Sorriso gengival<\/strong>: quando um excesso de tecido gengival (ou gengiva) \u00e9 mostrado ao sorrir.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a9e258 e-flex e-con-boxed e-con e-parent\" data-id=\"9a9e258\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c9c823b e-con-full e-flex e-con e-child\" data-id=\"c9c823b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf524fd elementor-widget elementor-widget-heading\" data-id=\"bf524fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Onde se deve ir para resolver os problemas acima?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edf6ef3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"edf6ef3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Uma pessoa que identifica esses problemas pode ir a um centro especializado em cirurgia maxilo-facial e\/ou ao seu ortodontista para uma consulta inicial.<\/p>\n<p>Os dois profissionais avaliam as queixas e expectativas do individuo, a situa\u00e7\u00e3o dent\u00e1ria, a oclus\u00e3o e o tamanho dos maxilares, a harmonia facial e decidem se o tratamento ortod\u00f4ntico \u00e9 suficiente ou se a cirurgia maxilo-facial \u00e9 necess\u00e1ria.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d55108 elementor-widget elementor-widget-heading\" data-id=\"3d55108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Por que \u00e9 necess\u00e1rio tratar a maloclus\u00e3o?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1da8bf elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b1da8bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No caso de uma m\u00e1 oclus\u00e3o, os tecidos que envolvem o dente s\u00e3o lesionados ao mastigar os alimentos, a inflama\u00e7\u00e3o ocorre e o osso come\u00e7a a perder espessura. <\/p>\n<p>\u00c0 medida que os ossos ficam finos, a mobilidade dos dentes aumenta e podem aparecer espa\u00e7os entre os dentes. Por outro lado, se os dentes estiverem na posi\u00e7\u00e3o errada, a placa dent\u00e1ria come\u00e7a a acumular-se rapidamente e causa inflama\u00e7\u00e3o dos tecidos que envolvem o dente; ent\u00e3o a c\u00e1rie danifica os dentes.<\/p>\n<p>Em algumas ocasi\u00f5es a maloclus\u00e3o pode criar les\u00f5es na articula\u00e7\u00e3o temporomandibular devido a sobrecarga.<\/p>\n<p>Finalmente, as maloclus\u00f5es t\u00eam um forte impacto negativo na est\u00e9tica do sorriso.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bfc46dd e-con-full e-flex e-con e-child\" data-id=\"bfc46dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00140ca elementor-widget elementor-widget-image\" data-id=\"00140ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1-819x1024.webp\" class=\"attachment-large size-large wp-image-10394\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1-819x1024.webp 819w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1-240x300.webp 240w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1-768x960.webp 768w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1-1229x1536.webp 1229w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1.webp 1300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-befd7a6 e-flex e-con-boxed e-con e-parent\" data-id=\"befd7a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eb6be2c e-con-full e-flex e-con e-child\" data-id=\"eb6be2c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-865cd56 elementor-widget elementor-widget-image\" data-id=\"865cd56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"628\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_134122-Maxillofacial-Surgery.webp\" class=\"attachment-large size-large wp-image-5564\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_134122-Maxillofacial-Surgery.webp 588w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_134122-Maxillofacial-Surgery-281x300.webp 281w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-978aad8 e-con-full e-flex e-con e-child\" data-id=\"978aad8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc2c1ba elementor-widget elementor-widget-heading\" data-id=\"fc2c1ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quando pode come\u00e7ar o tratamento ortod\u00f4ntico?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eb9400 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6eb9400\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c9 de extrema import\u00e2ncia notar o crescimento incorreto dos maxilares em crian\u00e7as de 9 a 13 anos de idade, pois, justamente nessa idade, \u00e9 poss\u00edvel corrigir a situa\u00e7\u00e3o atrav\u00e9s da aplica\u00e7\u00e3o de aparelhos ortod\u00f4nticos funcionais. O tratamento dura aproximadamente um ano e meio. <\/p>\n<p>No caso de pessoas acima de 13 anos de idade, se j\u00e1 est\u00e1 estabelecida a altera\u00e7\u00e3o maxilar, pode-se iniciar o tratamento ortod\u00f4ntico. A dura\u00e7\u00e3o do per\u00edodo de tratamento \u00e9 de 1 a 2 anos. <\/p>\n<p>N\u00e3o h\u00e1 limita\u00e7\u00f5es relacionadas com a idade para o tratamento ortod\u00f4ntico; entretanto, o tratamento ortod\u00f4ntico de pessoas idosas pode ser mais complicado e durar mais. Com o passar dos anos, ocorre a reabsor\u00e7\u00e3o do tecido \u00f3sseo, o que torna o manejo ortod\u00f4ntico mais complicado. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-559d9d8 elementor-widget elementor-widget-heading\" data-id=\"559d9d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quando \u00e9 realizado o tratamento cir\u00fargico?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dba97fc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"dba97fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A cirurgia maxilo-facial pode ser realizada em individuos com mais de 18 anos de idade. O tratamento completo ortodontia-cirurgia-ortodontia leva de 2 a 3 anos, em coopera\u00e7\u00e3o com o ortodontista. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-651f4ce elementor-widget elementor-widget-button\" data-id=\"651f4ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#footer_contactos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Marcar Consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f459753 e-flex e-con-boxed e-con e-parent\" data-id=\"f459753\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-172191f e-con-full e-flex e-con e-child\" data-id=\"172191f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bddd77 elementor-widget elementor-widget-heading\" data-id=\"5bddd77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Em que consiste a primeira consulta de cirurgia maxilo-facial?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1d9815 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e1d9815\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Um cirurgi\u00e3o avalia o caso e recolhe algumas informa\u00e7\u00f5es necess\u00e1rias, tais como: queixas e exames, problemas na oclus\u00e3o dent\u00e1ria e se sofre ou sofreu de alguma doen\u00e7a ou alergia.<\/p>\n<p>Todas essas informa\u00e7\u00f5es ser\u00e3o coletadas juntamente com a an\u00e1lise facial e dent\u00e1ria para um registo completo do caso cl\u00ednico; essas informa\u00e7\u00f5es ser\u00e3o passadas ao ortodontista, a fim de elaborar o plano de tratamento mais indicado. Se o individuo n\u00e3o tiver um ortodontista de refer\u00eancia, ser\u00e3o fornecidas informa\u00e7\u00f5es para a escolha mais apropriada. <\/p>\n<p>Se j\u00e1 tem ortodontista deve levar consigo: uma radiografia panor\u00e2mica da cavidade oral (ortopantomografia), uma radiografia lateral da cabe\u00e7a e modelos dent\u00e1rios feitos em gesso. Se n\u00e3o tem ser\u00e3o realizadas a planifica\u00e7\u00e3o da realiza\u00e7\u00e3o das mesmas. <\/p>\n<p>Para registo e an\u00e1lise cl\u00ednica, ser\u00e3o tiradas fotografias da frente e do perfil.<\/p>\n<p>Durante a apresenta\u00e7\u00e3o do plano de tratamento, aspetos como detalhes do tratamento, dura\u00e7\u00e3o aproximada, riscos e poss\u00edveis complica\u00e7\u00f5es ser\u00e3o discutidos.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09ca3a7 e-flex e-con-boxed e-con e-parent\" data-id=\"09ca3a7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9cc8cad e-flex e-con-boxed e-con e-parent\" data-id=\"9cc8cad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-660b597 e-con-full e-flex e-con e-child\" data-id=\"660b597\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-944586d elementor-widget elementor-widget-heading\" data-id=\"944586d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O que acontece durante o tratamento ortod\u00f4ntico pr\u00e9-cir\u00fargico?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7034930 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7034930\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Todos os dentes do siso devem ser removidos antes do in\u00edcio do tratamento ortod\u00f4ntico. A extra\u00e7\u00e3o pode ser realizada antes do inicio do tratamento ortod\u00f4ntico ou durante o mesmo, mas em todos os casos, pelo menos 6 meses antes da cirurgia maxilo-facial. <\/p>\n<p>O objectivo da ortodontia pr\u00e9-operat\u00f3ria \u00e9 remover toda a compensa\u00e7\u00e3o dent\u00e1ria existente e fornecer ao cirurgi\u00e3o uma estrutura est\u00e1vel e adequada entre as arcadas superior e inferior, alinhando os dentes de modo a realizar os movimentos esquel\u00e9ticos pretendidos.<\/p>\n<p>Este objectivo \u00e9 geralmente alcan\u00e7ado em 12-18 meses. <\/p>\n<p>Uma vez que os dentes estejam na posi\u00e7\u00e3o ideal para operar, \u00e9 realizado o estudo pr\u00e9-operat\u00f3rio, realizando um CAT scan 3D, novos registros dent\u00e1rios e fotografias, que ser\u00e3o estudados pelo cirurgi\u00e3o com o objetivo de planear perfeitamente o caso com precis\u00e3o milim\u00e9trica, com o suporte de m\u00e9todos de programa\u00e7\u00e3o digital 3D.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15014e6 e-flex e-con-boxed e-con e-parent\" data-id=\"15014e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-406d1c0 e-con-full e-flex e-con e-child\" data-id=\"406d1c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e90c269 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e90c269\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O planeamento virtual em cirurgia maxilo-facial foi introduzido na \u00faltima d\u00e9cada e oferece ao cirurgi\u00e3o a melhor ferramenta de diagn\u00f3stico e planeamento da atualidade. Com a utiliza\u00e7\u00e3o da Tomografia Cone Beam, scaneamento dos modelos e softwares de planeamento 3D podemos planear, simular e executar a cirurgia com precis\u00e3o em mil\u00edmetros. <\/p>\n<p>Desta maneira, o cirurgi\u00e3o possui a possibilidade de trocar informa\u00e7\u00f5es juntamente com o ortodontista, simular e avaliar as possibilidades cir\u00fargicas antes mesmo de executar a cirurgia, garantindo maior previsibilidade do caso e maior satisfa\u00e7\u00e3o da pessoa.<\/p>\n<p>Al\u00e9m de auxiliar no planeamento, o software 3D garante maior n\u00famero de informa\u00e7\u00f5es e precis\u00e3o durante a execu\u00e7\u00e3o da cirurgia propriamente dita, reduzindo o tempo e o trauma cir\u00fargico durante o procedimento.<\/p>\n<p>Uma semana antes da opera\u00e7\u00e3o \u00e9 realizada uma avalia\u00e7\u00e3o muscular dos m\u00fasculos cervico-facial e de degluti\u00e7\u00e3o para avaliar novamente o individuo funcionalmente, com o objetivo de compar\u00e1-lo com as terapias que ser\u00e3o realizadas no per\u00edodo p\u00f3s-operat\u00f3rio. Os pedidos de exames pr\u00e9-operat\u00f3rios ser\u00e3o entregues e avaliados pelo cirurgi\u00e3o e pelo anestesista. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-698711a elementor-widget elementor-widget-button\" data-id=\"698711a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#footer_contactos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Marcar Consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d0bd90 e-con-full e-flex e-con e-child\" data-id=\"1d0bd90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d58812d elementor-widget elementor-widget-image\" data-id=\"d58812d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"640\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1024x819.webp\" class=\"attachment-large size-large wp-image-10398\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1024x819.webp 1024w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-300x240.webp 300w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-768x614.webp 768w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery-1536x1229.webp 1536w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2025\/03\/Maxillofacial-Surgery.webp 1760w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83de160 e-flex e-con-boxed e-con e-parent\" data-id=\"83de160\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6afc97b e-con-full e-flex e-con e-child\" data-id=\"6afc97b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23c7437 elementor-widget elementor-widget-image\" data-id=\"23c7437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"409\" height=\"353\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_135225-Maxillofacial-Surgery.webp\" class=\"attachment-large size-large wp-image-5570\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_135225-Maxillofacial-Surgery.webp 409w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_135225-Maxillofacial-Surgery-300x259.webp 300w\" sizes=\"auto, (max-width: 409px) 100vw, 409px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4732583 e-con-full e-flex e-con e-child\" data-id=\"4732583\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc53519 elementor-widget elementor-widget-heading\" data-id=\"cc53519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quais s\u00e3o os novos avan\u00e7os na cirurgia maxilo-facial?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f047166 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f047166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Na planifica\u00e7\u00e3o da cirurgia por meio da tecnologia 3D, como falado no ponto anterior, conseguindo uma maior previs\u00e3o e precis\u00e3o cir\u00fargica.<\/p>\n<p><strong>Na execu\u00e7\u00e3o da cirurgia: cirurgia ultrass\u00f3nica ou cirurgia assistida por piezoel\u00e9trico, realizando os cortes no osso (osteotomia) por ultrassons, sem atingir os tecidos moles. \u00c9 um procedimento muito mais preciso e menos traum\u00e1tico para os tecido duros. 5 5<\/strong><\/p>\n<p><strong>No p\u00f3s-operat\u00f3rio: m\u00e1scara de arrefecimento facial Hiloterm \u00ae. Hilotherm \u00e9 um equipamento que funciona com acess\u00f3rios anat\u00f4micos para todas as partes do corpo, sendo indicado como m\u00e9todo mais eficaz e moderno na recupera\u00e7\u00e3o do trauma p\u00f3s cir\u00fargico pelo meio da crioterapia\/termoterapia eficaz para al\u00edvio da dor e do incha\u00e7o ao manter a face com uma temperatura cont\u00ednua e controlada nos 15\u00baC.<\/strong><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db37419 e-flex e-con-boxed e-con e-parent\" data-id=\"db37419\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3b8f5de e-con-full e-flex e-con e-child\" data-id=\"3b8f5de\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06cd53c elementor-widget elementor-widget-heading\" data-id=\"06cd53c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O que devo saber antes da cirurgia?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0037b47 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0037b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A cirurgia maxilo-facial \u00e9 um procedimento planejado e, portanto, n\u00e3o \u00e9 realizada se a pessoa tiver uma infec\u00e7\u00e3o ativa, caso em que a interven\u00e7\u00e3o ser\u00e1 adiada at\u00e9 que a situa\u00e7\u00e3o cl\u00ednica seja adequada;<\/p>\n<p>O est\u00f4mago deve estar vazio antes da cirurgia;<\/p>\n<p>Comer e beber de manh\u00e3 antes da cirurgia \u00e9 estritamente proibido. \u00c9 uma regra extremamente importante \u2013 se o conte\u00fado estomacal entrar nas vias respirat\u00f3rias, pode levar a um resultado fatal; <\/p>\n<p>A opera\u00e7\u00e3o \u00e9 sempre realizada sob anestesia geral.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56838f2 e-flex e-con-boxed e-con e-parent\" data-id=\"56838f2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-71d1bfc e-con-full e-flex e-con e-child\" data-id=\"71d1bfc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b561c elementor-widget elementor-widget-heading\" data-id=\"c5b561c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quais s\u00e3o as normas de alimenta\u00e7\u00e3o e higiene ap\u00f3s a cirurgia?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f031a88 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f031a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante as primeiras semanas ap\u00f3s a cirurgia, a alimenta\u00e7\u00e3o deve ser baseada em l\u00edquidos, depois o cirurgi\u00e3o orientar\u00e1 a introdu\u00e7\u00e3o progressiva dos alimentos.<\/p>\n<p>A higiene oral \u00e9 um elemento fundamental nesta fase e deve ser realizada com escova de pontas macias v\u00e1rias vezes ao dia, juntamente com enxaguamentos orais e a aplica\u00e7\u00e3o de gel oral anti-s\u00e9ptico.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c25382 e-flex e-con-boxed e-con e-parent\" data-id=\"8c25382\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64b0363 e-flex e-con-boxed e-con e-parent\" data-id=\"64b0363\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-81fdf8d e-con-full e-flex e-con e-child\" data-id=\"81fdf8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-987eaef elementor-widget elementor-widget-heading\" data-id=\"987eaef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tenho de usar el\u00e1sticos nos meus dentes depois da cirurgia?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4adb08a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4adb08a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A coloca\u00e7\u00e3o correta dos el\u00e1sticos \u00e9 fundamental para um resultado correto, a partir do momento em que se termina a interven\u00e7\u00e3o ser\u00e1 colocada para ajudar a estabilidade da mesma.  <\/p>\n<p>Estes devem ser retirados durante as refei\u00e7\u00f5es e colocados novamente ap\u00f3s a higiene oral, devem ser completamente trocados uma vez por dia. O cirurgi\u00e3o orientar\u00e1 a sua coloca\u00e7\u00e3o durante as primeiras semanas ap\u00f3s a cirurgia maxilo-facial. Progressivamente, os tempos sem suporte el\u00e1stico ser\u00e3o maiores e os el\u00e1sticos ser\u00e3o de menor for\u00e7a.  <\/p>\n<p>O cirurgi\u00e3o deve acompanhar o individuo pelo menos at\u00e9 \u00e0 remo\u00e7\u00e3o do aparelho ortod\u00f4ntico.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acba23a elementor-widget elementor-widget-button\" data-id=\"acba23a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#footer_contactos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Marcar Consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36e67a8 e-flex e-con-boxed e-con e-parent\" data-id=\"36e67a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5b3da0a e-con-full e-flex e-con e-child\" data-id=\"5b3da0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a28f8e elementor-widget elementor-widget-heading\" data-id=\"1a28f8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tipos de Cirurgia Maxilo-facial?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c05e45 e-flex e-con-boxed e-con e-parent\" data-id=\"0c05e45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f3ae2b4 e-con-full e-flex e-con e-child\" data-id=\"f3ae2b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f12ef81 elementor-widget elementor-widget-image\" data-id=\"f12ef81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"392\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_135854-Maxillofacial-Surgery.webp\" class=\"attachment-large size-large wp-image-5574\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_135854-Maxillofacial-Surgery.webp 615w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_135854-Maxillofacial-Surgery-300x191.webp 300w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a51a874 e-con-full e-flex e-con e-child\" data-id=\"a51a874\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b54976 elementor-widget elementor-widget-heading\" data-id=\"4b54976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cirurgia na Maxila<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1196011 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1196011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A cirurgia maxilo-facial na maxila \u00e9 realizada para colocar o maxilar na posi\u00e7\u00e3o correta para alcan\u00e7ar a harmonia facial, e o mais importante, uma recupera\u00e7\u00e3o da funcionalidade deste osso, que \u00e9 a chave para mastigar, respirar e falar.<\/p>\n<p>Esse procedimento \u00e9 realizado para corrigir v\u00e1rias deformidades faciais, como o prognatismo mandibular ou Classe 3, mordida aberta ou sorriso gengival.<\/p>\n<p>A cirurgia maxilo-facial do maxilar consiste num corte no osso do maxilar chamado osteotomia Le Fort I, que permite o avan\u00e7o, retrus\u00e3o, alongamento, encurtamento ou rota\u00e7\u00e3o do osso do maxilar. Uma vez na posi\u00e7\u00e3o desejada, o maxilar \u00e9 fixado com placas e parafusos de tit\u00e2nio, um material completamente biocompat\u00edvel. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13869d3 e-flex e-con-boxed e-con e-parent\" data-id=\"13869d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-61a3ef4 e-con-full e-flex e-con e-child\" data-id=\"61a3ef4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8c4d537 elementor-widget elementor-widget-heading\" data-id=\"8c4d537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cirurgia na Mand\u00edbula<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b0f22c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"8b0f22c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Devido aos riscos envolvidos na cirurgia de redu\u00e7\u00e3o da mand\u00edbula (estreitamento das vias a\u00e9reas), a cirurgia maxilo-facial mais comumente praticada na mand\u00edbula \u00e9 a cirurgia de avan\u00e7o mandibular. <\/p>\n<p>Este procedimento \u00e9 necess\u00e1rio quando as pessoas t\u00eam uma mand\u00edbula pequena que \u00e9 retra\u00edda em rela\u00e7\u00e3o \u00e0 maxila, uma condi\u00e7\u00e3o conhecida como retrognatia ou classe II. Reserva-se o recuo mandibular nos casos de prognatismo mandibular acentuado nas classes III, normalmente, em combina\u00e7\u00e3o com cirurgia maxilar de avan\u00e7o, no contexto de cirurgia bimaxilar.<\/p>\n<p>Este tipo de malforma\u00e7\u00e3o afecta especialmente a harmonia da face inferior e causa v\u00e1rios problemas funcionais, tais como a apneia do sono.<\/p>\n<p>A cirurgia de avan\u00e7o mandibular consiste num corte de cada lado do osso da mand\u00edbula chamado osteotomia sagital bilateral, um avan\u00e7o do osso e fixa\u00e7\u00e3o do osso na nova posi\u00e7\u00e3o atrav\u00e9s de placas de tit\u00e2nio, um material completamente biocompat\u00edvel.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-978412d e-con-full e-flex e-con e-child\" data-id=\"978412d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53f23fa elementor-widget elementor-widget-image\" data-id=\"53f23fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"443\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_140103-Maxillofacial-Surgery.webp\" class=\"attachment-large size-large wp-image-5576\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_140103-Maxillofacial-Surgery.webp 615w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_140103-Maxillofacial-Surgery-300x216.webp 300w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-603d9f3 e-flex e-con-boxed e-con e-parent\" data-id=\"603d9f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2d993bc e-con-full e-flex e-con e-child\" data-id=\"2d993bc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e57513e elementor-widget elementor-widget-image\" data-id=\"e57513e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"587\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_140526-Maxillofacial-Surgery.webp\" class=\"attachment-large size-large wp-image-5552\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_140526-Maxillofacial-Surgery.webp 615w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_140526-Maxillofacial-Surgery-300x286.webp 300w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64aaee3 e-con-full e-flex e-con e-child\" data-id=\"64aaee3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f17d93e elementor-widget elementor-widget-heading\" data-id=\"f17d93e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cirurgia Maxilomandibular ou Bimaxilar<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3911c95 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3911c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Na maioria das pessoas com altera\u00e7\u00f5es dentofaciais \u00e9 necess\u00e1rio reposicionar a maxila e a mand\u00edbula para alcan\u00e7ar uma correta oclus\u00e3o e harmonia facial. <\/p>\n<p>Esse procedimento \u00e9 conhecido como cirurgia maxilomandibular ou cirurgia maxilo-facial bimaxilar.<\/p>\n<p>A cirurgia maxilo-facial bimaxilar \u00e9 usada para tratar as seguintes malforma\u00e7\u00f5es: Classe 2, Classe 3, assimetria facial, ou mordida aberta, entre outras, quando uma cirurgia monomaxilar n\u00e3o \u00e9 suficiente para reparar os problemas do individuo.<\/p>\n<p>A mentoplastia, como ser\u00e1 explicado mais \u00e0 frente, \u00e9 uma cirurgia ao queixo. Para atingir um resultado de excel\u00eancia, nos casos em que \u00e9 necess\u00e1ria, esta deve ser realizada no mesmo momento da cirurgia maxilo-facial.<\/p>\n<p>A cirurgia \u00e9 realizada por incis\u00f5es dentro da boca, as feridas demoram dez dias a cicatrizar, os pontos s\u00e3o reabsorv\u00edveis e, em m\u00e9dia, a mand\u00edbula \u00e9 consolidada em 2 meses e a maxila \u00e9 consolidada em 4 meses. <\/p>\n<p>A estadia m\u00e9dia no local da cirurgia \u00e9 de um dia. Ser\u00e1 colocado um equipamento de arrefecimento facial para minimizar o edema p\u00f3s-operat\u00f3rio e a drenagem linf\u00e1tica tamb\u00e9m ser\u00e1 realizada no segundo dia de p\u00f3s-operat\u00f3rio.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d873d1 e-flex e-con-boxed e-con e-parent\" data-id=\"3d873d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bb805b0 e-con-full e-flex e-con e-child\" data-id=\"bb805b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dbf67b2 elementor-widget elementor-widget-heading\" data-id=\"dbf67b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mentoplastia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c07205 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4c07205\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mentoplastia \u00e9 uma cirurgia ambulat\u00f3ria ao queixo, muito segura e com grandes resultados. Em algumas partes do mundo, esta cirurgia chega mesmo a suplantar outro tipo de cirurgias est\u00e9ticas como as lipoesculturas ou as mamoplastias. <\/p>\n<p>O queixo, al\u00e9m de ser uma das partes mais importantes na defini\u00e7\u00e3o da nossa face, \u00e9 tamb\u00e9m um dos sinais faciais de g\u00e9nero, o que faz com que haja cada vez mais pessoas recorram \u00e0 mentoplastia para aumentar, diminuir ou simetrizar a sua face.<\/p>\n<p>Esta cirurgia \u00e9 realizada atrav\u00e9s de uma pequena incis\u00e3o dentro da boca (n\u00e3o deixando cicatriz), onde \u00e9 aumentado ou diminuido o osso do mento, sendo que tamb\u00e9m se pode recorrer a uma pr\u00f3tese \u00e0 medida para se conseguir o resultado est\u00e9tico maxilo-facial desejado.<\/p>\n<p>Este tipo de t\u00e9cnicas deixam um resultado permanente no individuo. Existem outras t\u00e9cnicas como a infiltra\u00e7\u00e3o de acido hialur\u00f3nico ou a infiltra\u00e7\u00e3o de gordura recolhida por lipoaspira\u00e7\u00e3o das coxas ou barriga, para tratamentos do queixo.<\/p>\n<p>Nos \u00faltimos tempos a modelagem do contorno do queixo ou contornoplastia tem-se revelado como uma t\u00e9cnica altamente eficiente na est\u00e9tica maxilo-facial.<\/p>\n<p>Uma das grandes vantagens da mentoplastia \u00e9 o seu p\u00f3s-operat\u00f3rio leve em rela\u00e7\u00e3o a outras cirurgias est\u00e9ticas e a evid\u00eancia do resultado final num curto espa\u00e7o de tempo.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9373629 elementor-widget elementor-widget-button\" data-id=\"9373629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#footer_contactos\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Marcar Consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cffcf76 e-con-full e-flex e-con e-child\" data-id=\"cffcf76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d60c0 elementor-widget elementor-widget-image\" data-id=\"f5d60c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"597\" height=\"615\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_141002-Maxillofacial-Surgery.webp\" class=\"attachment-large size-large wp-image-5578\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_141002-Maxillofacial-Surgery.webp 597w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/PSX_20210917_141002-Maxillofacial-Surgery-291x300.webp 291w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f804af e-flex e-con-boxed e-con e-parent\" data-id=\"1f804af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3b531ad e-con-full e-flex e-con e-child\" data-id=\"3b531ad\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b3a1b7 elementor-widget elementor-widget-heading\" data-id=\"9b3a1b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Patologias da Deformidade Dento-facial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0f88c7 elementor-widget elementor-widget-heading\" data-id=\"a0f88c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Apneia do Sono<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26beb22 elementor-widget elementor-widget-heading\" data-id=\"26beb22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Apneia do sono e como resolver com cirurgia maxilo-facial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd5df60 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fd5df60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A S\u00edndrome da Apneia Obstrutiva do Sono (SAOS) \u00e9 uma doen\u00e7a que consiste em repetidos epis\u00f3dios de pausas respirat\u00f3rias durante o sono, as apneias, geralmente mais longas que 10 segundos. A principal causa de obstru\u00e7\u00e3o \u00e9 o colapso das paredes da via a\u00e9rea superior. <\/p>\n<p>A S\u00edndrome da Apneia Obstrutiva do Sono afecta pouco mais de 25% da popula\u00e7\u00e3o, condicionando muito negativamente a qualidade de vida de quem a sofre.<\/p>\n<p>N\u00e3o s\u00f3 ao seu descanso durante a noite, que em casos extremos pode at\u00e9 levar \u00e0 morte, mas tamb\u00e9m \u00e0 actividade di\u00e1ria, acompanhada de sonol\u00eancia e fadiga cr\u00f3nica.<\/p>\n<p>Ainda mais grave, a Apneia do Sono causa uma redu\u00e7\u00e3o do oxig\u00e9nio transportado pelo sangue, levando a uma tens\u00e3o arterial elevada, doen\u00e7as cardiovasculares, dist\u00farbios metab\u00f3licos e hormonais e aumento do risco de acidentes.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc090d4 elementor-widget elementor-widget-heading\" data-id=\"cc090d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sintomas associados \u00e0 apneia do sono<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deaf704 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"deaf704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A presen\u00e7a de dois dos seguintes sintomas, na aus\u00eancia de outras causas, pode ser um indicador da S\u00edndrome da Apneia Obstrutiva do Sono:<\/p>\n<ul>\n<li>Ronco irregular, alto e interrompido (Acompanhado de apneia do sono);<\/li>\n<li>Fadiga durante o dia;<\/li>\n<li>Fadiga cr\u00f3nica.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2158db elementor-widget elementor-widget-heading\" data-id=\"e2158db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teste diagn\u00f3stico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fdee74 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4fdee74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O diagn\u00f3stico da Apn\u00e9ia do Sono \u00e9 feito atrav\u00e9s de um teste chamado polissonografia, que monitora v\u00e1rias vari\u00e1veis durante o sono, usando dispositivos especiais.<\/p>\n<p>Este exame \u00e9 realizado pela Neurofisiologia, portanto os cirurgi\u00f5es maxilofaciais, sendo uma doen\u00e7a multidisciplinar, devem coordenar, entre todos os especialistas, geralmente pneumologistas, neurofisiologistas e otorrinolaringologistas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ee24cd e-flex e-con-boxed e-con e-parent\" data-id=\"8ee24cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a649aa1 e-con-full e-flex e-con e-child\" data-id=\"a649aa1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb4898d elementor-widget elementor-widget-image\" data-id=\"cb4898d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"459\" src=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/Maxillofacial-Surgery-2.webp\" class=\"attachment-large size-large wp-image-5580\" alt=\"\" srcset=\"https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/Maxillofacial-Surgery-2.webp 615w, https:\/\/bouchedentalgroup.lu\/wp-content\/uploads\/2024\/09\/Maxillofacial-Surgery-2-300x224.webp 300w\" sizes=\"auto, (max-width: 615px) 100vw, 615px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab113ef e-con-full e-flex e-con e-child\" data-id=\"ab113ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae3e491 elementor-widget elementor-widget-heading\" data-id=\"ae3e491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tratamento da apneia do sono: n\u00edveis de ac\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0281c00 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0281c00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quatro n\u00edveis de desempenho s\u00e3o normalmente descritos no tratamento da S\u00edndrome da Apneia Obstrutiva do Sono:<\/p>\n<ul>\n<li>Perda de peso;<\/li>\n<li>CPAP<\/li>\n<li>Talas de avan\u00e7o mandibular;<\/li>\n<li>Cirurgia ortogn\u00e1tica.<\/li>\n<\/ul>\n<p>Um dos tratamentos recomendados h\u00e1 muitos anos \u00e9 o CPAP, acr\u00f3nimo de \u201cContinuous Positive Airway Pressure\u201d, um dispositivo nocturno constitu\u00eddo por uma m\u00e1scara ligada a uma m\u00e1quina, que sopra em ar comprimido e evita o colapso das vias respirat\u00f3rias do individuo.<\/p>\n<p>A maioria das pessoas que sofreram de Apn\u00e9ia do Sono descrevem o CPAP como uma m\u00e1quina \u201cinfernal\u201d. A intoler\u00e2ncia ao ru\u00eddo e \u00e0 m\u00e1scara, a congest\u00e3o nasal e a irrita\u00e7\u00e3o das mucosas, fazem com que at\u00e9 70% das pessoas queiram abandonar o CPAP e encontrar uma alternativa muito mais confort\u00e1vel e eficaz. <\/p>\n<p>Por outro lado, as talas dent\u00e1rias de avan\u00e7o mandibular s\u00e3o um elemento de diagn\u00f3stico e tamb\u00e9m uma solu\u00e7\u00e3o tempor\u00e1ria para casos leves de Apn\u00e9ia do Sono. De acordo com estudos recentes, o uso prolongado desta cinta pode causar altera\u00e7\u00f5es na forma de morder e deteriora\u00e7\u00e3o da articula\u00e7\u00e3o temporomandibular. <\/p>\n<p>Gra\u00e7as \u00e0 cont\u00ednua dedica\u00e7\u00e3o e intensa pesquisa da S\u00edndrome da Apneia Obstrutiva do Sono, hoje os especialistas do Instituto Maxilofacial, juntamente com outros grupos a n\u00edvel internacional, t\u00eam demonstrado cientificamente que a cirurgia maxilo-facial \u00e9 a solu\u00e7\u00e3o definitiva para este grave problema em pessoas que apresentam deformidades dentofaciais.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cirurgia Maxilo-facial O departamento de cirurgia maxilo-facial, est\u00e1 dedicado ao diagn\u00f3stico e tratamento cir\u00fargico das altera\u00e7\u00f5es no desenvolvimento \u00f3sseo facial do adulto. Designa-se por cirurgia maxilo-facial a interven\u00e7\u00e3o que corrige as assimetrias dentofaciais com o objetivo de alcan\u00e7ar um equil\u00edbrio perfeito da face e dos dentes. As dismorfias dentofaciais s\u00e3o bastante frequentes na popula\u00e7\u00e3o em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5998","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bouchedentalgroup.lu\/pt-pt\/wp-json\/wp\/v2\/pages\/5998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bouchedentalgroup.lu\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bouchedentalgroup.lu\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bouchedentalgroup.lu\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bouchedentalgroup.lu\/pt-pt\/wp-json\/wp\/v2\/comments?post=5998"}],"version-history":[{"count":0,"href":"https:\/\/bouchedentalgroup.lu\/pt-pt\/wp-json\/wp\/v2\/pages\/5998\/revisions"}],"wp:attachment":[{"href":"https:\/\/bouchedentalgroup.lu\/pt-pt\/wp-json\/wp\/v2\/media?parent=5998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}